{"id":21819,"date":"2023-12-19T15:41:22","date_gmt":"2023-12-19T13:41:22","guid":{"rendered":"https:\/\/dim4you.com.ua\/property\/proekt-doma-maykl\/"},"modified":"2026-07-08T19:32:30","modified_gmt":"2026-07-08T16:32:30","slug":"proekt-doma-maykl","status":"publish","type":"property","link":"https:\/\/dim4you.com.ua\/ru\/property\/proekt-doma-maykl\/","title":{"rendered":"\u041f\u0440\u043e\u0435\u043a\u0442 \u0414\u043e\u043c\u0430 \u041c\u0430\u0439\u043a\u043b"},"content":{"rendered":"\n<p>\u0421\u043e\u0432\u0440\u0435\u043c\u0435\u043d\u043d\u044b\u0439 \u043f\u0440\u043e\u0435\u043a\u0442 \u0434\u0432\u0443\u0445\u044d\u0442\u0430\u0436\u043d\u043e\u0433\u043e \u0434\u043e\u043c\u0430 \u0441 \u0433\u0430\u0440\u0430\u0436\u043e\u043c \u0438 \u0442\u0435\u0440\u0440\u0430\u0441\u043e\u0439. \u041f\u043b\u0430\u043d\u0438\u0440\u043e\u0432\u043a\u0430 \u0434\u043e\u043c\u0430 \u041c\u0430\u0439\u043a\u043b \u043f\u0440\u0435\u0434\u0443\u0441\u043c\u0430\u0442\u0440\u0438\u0432\u0430\u0435\u0442 \u043f\u0440\u043e\u0441\u0442\u043e\u0440\u043d\u0443\u044e \u0433\u043e\u0441\u0442\u0438\u043d\u0443\u044e \u0441 \u0431\u043e\u043b\u044c\u0448\u0438\u043c\u0438 \u043e\u043a\u043d\u0430\u043c\u0438, \u043a\u0443\u0445\u043d\u044e \u0441\u0442\u0443\u0434\u0438\u044e \u0441 \u0443\u0434\u043e\u0431\u043d\u043e\u0439 \u043a\u043b\u0430\u0434\u043e\u0432\u043e\u0439 \u0438 \u043a\u0430\u0431\u0438\u043d\u0435\u0442 \u043d\u0430 \u043f\u0435\u0440\u0432\u043e\u043c \u044d\u0442\u0430\u0436\u0435.<\/p>\n\n\n\n<p>\u041d\u0430 \u0432\u0442\u043e\u0440\u043e\u043c \u044d\u0442\u0430\u0436\u0435 \u0440\u0430\u0437\u043c\u0435\u0449\u0435\u043d\u044b 3 \u0441\u043f\u0430\u043b\u044c\u043d\u0438, \u0441\u0430\u043d\u0443\u0437\u0435\u043b \u0438 \u043e\u0442\u0434\u0435\u043b\u044c\u043d\u0430\u044f \u043f\u0440\u0430\u0447\u0435\u0447\u043d\u0430\u044f.<\/p>\n\n\n\n<p>\u041f\u0440\u043e\u0435\u043a\u0442 \u0434\u0432\u0443\u0445\u044d\u0442\u0430\u0436\u043d\u043e\u0433\u043e \u0434\u043e\u043c\u0430 \u041c\u0430\u0439\u043a\u043b \u2014 \u0438\u0434\u0435\u0430\u043b\u044c\u043d\u043e\u0435 \u0441\u043e\u0447\u0435\u0442\u0430\u043d\u0438\u0435 \u044d\u0440\u0433\u043e\u043d\u043e\u043c\u0438\u043a\u0438 \u0438 \u0441\u043e\u0432\u0440\u0435\u043c\u0435\u043d\u043d\u043e\u0441\u0442\u0438.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0421\u043e\u0432\u0440\u0435\u043c\u0435\u043d\u043d\u044b\u0439 \u043f\u0440\u043e\u0435\u043a\u0442 \u0434\u0432\u0443\u0445\u044d\u0442\u0430\u0436\u043d\u043e\u0433\u043e \u0434\u043e\u043c\u0430 \u0441 \u0433\u0430\u0440\u0430\u0436\u043e\u043c \u0438 \u0442\u0435\u0440\u0440\u0430\u0441\u043e\u0439. \u041f\u043b\u0430\u043d\u0438\u0440\u043e\u0432\u043a\u0430 \u0434\u043e\u043c\u0430 \u041c\u0430\u0439\u043a\u043b \u043f\u0440\u0435\u0434\u0443\u0441\u043c\u0430\u0442\u0440\u0438\u0432\u0430\u0435\u0442 \u043f\u0440\u043e\u0441\u0442\u043e\u0440\u043d\u0443\u044e \u0433\u043e\u0441\u0442\u0438\u043d\u0443\u044e \u0441 \u0431\u043e\u043b\u044c\u0448\u0438\u043c\u0438 \u043e\u043a\u043d\u0430\u043c\u0438, \u043a\u0443\u0445\u043d\u044e \u0441\u0442\u0443\u0434\u0438\u044e \u0441 \u0443\u0434\u043e\u0431\u043d\u043e\u0439 \u043a\u043b\u0430\u0434\u043e\u0432\u043e\u0439 \u0438 \u043a\u0430\u0431\u0438\u043d\u0435\u0442 \u043d\u0430 \u043f\u0435\u0440\u0432\u043e\u043c \u044d\u0442\u0430\u0436\u0435. \u041d\u0430 \u0432\u0442\u043e\u0440\u043e\u043c \u044d\u0442\u0430\u0436\u0435 \u0440\u0430\u0437\u043c\u0435\u0449\u0435\u043d\u044b 3 \u0441\u043f\u0430\u043b\u044c\u043d\u0438, \u0441\u0430\u043d\u0443\u0437\u0435\u043b \u0438 \u043e\u0442\u0434\u0435\u043b\u044c\u043d\u0430\u044f \u043f\u0440\u0430\u0447\u0435\u0447\u043d\u0430\u044f. \u041f\u0440\u043e\u0435\u043a\u0442 \u0434\u0432\u0443\u0445\u044d\u0442\u0430\u0436\u043d\u043e\u0433\u043e \u0434\u043e\u043c\u0430 \u041c\u0430\u0439\u043a\u043b \u2014 \u0438\u0434\u0435\u0430\u043b\u044c\u043d\u043e\u0435 \u0441\u043e\u0447\u0435\u0442\u0430\u043d\u0438\u0435 \u044d\u0440\u0433\u043e\u043d\u043e\u043c\u0438\u043a\u0438 \u0438 \u0441\u043e\u0432\u0440\u0435\u043c\u0435\u043d\u043d\u043e\u0441\u0442\u0438.<\/p>\n","protected":false},"author":2,"featured_media":21783,"parent":0,"menu_order":0,"template":"","property_type":[116,156,117,120],"property_status":[],"property_feature":[],"property_label":[164],"acf":[],"property_meta":{"_alp_processed":["1783528351"],"_thumbnail_id":["21783"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"facades_0_image":["21800"],"facades_1_image":["21806"],"facades_2_image":["21809"],"facades_3_image":["21812"],"floor_plan_0_image":["21790"],"floor_plan_0_image_popup":["21787"],"floor_plan_1_image":["21793"],"floor_plan_1_image_popup":["21796"],"fave_property_price":["27500"],"fave_property_size":["195"],"fave_property_size_prefix":["31"],"fave_property_bedrooms":["3+1"],"fave_property_bathrooms":["2"],"fave_property_garage":["+"],"fave_property_year":["2"],"fave_property_id":["0023"],"fave_property_location":["25.68654,-80.431345,15"],"houzez_geolocation_lat":["25.68654"],"houzez_geolocation_long":["-80.431345"],"fave_property_map_street_view":["hide"],"fave_agent_display_option":["author_info"],"fave_agents":["-1"],"fave_property_agency":["-1"],"fave_prop_homeslider":["no"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"facades":["4"],"floor_plan":["2"],"floor_plan_0_table":["12"],"floor_plan_0_title":["\u041f\u043b\u0430\u043d 1-\u0433\u043e \u044d\u0442\u0430\u0436\u0430"],"floor_plan_1_table":["8"],"floor_plan_1_title":["\u041f\u043b\u0430\u043d 2-\u0433\u043e \u044d\u0442\u0430\u0436\u0430"],"rank_math_title":["\u041f\u0440\u043e\u0435\u043a\u0442 \u0434\u0432\u0443\u0445\u044d\u0442\u0430\u0436\u043d\u043e\u0433\u043e \u0434\u043e\u043c\u0430 \u0441 \u0433\u0430\u0440\u0430\u0436\u043e\u043c \u041c\u0430\u0439\u043a\u043b | \u0413\u043e\u0442\u043e\u0432\u044b\u0435 \u043f\u0440\u043e\u0435\u043a\u0442\u044b %sitename%"],"rank_math_description":["\u041c\u0430\u0439\u043a\u043b - \u043f\u0440\u043e\u0435\u043a\u0442 \u0434\u0432\u0443\u0445\u044d\u0442\u0430\u0436\u043d\u043e\u0433\u043e \u0434\u043e\u043c\u0430 \u0441 \u0442\u0435\u0440\u0440\u0430\u0441\u043e\u0439 \u0438 \u0433\u0430\u0440\u0430\u0436\u043e\u043c. 4 \u0441\u043f\u0430\u043b\u044c\u043d\u0438 \u0438 2 \u0432\u0430\u043d\u043d\u044b\u0435 \u043a\u043e\u043c\u043d\u0430\u0442\u044b. S=195\u043c2, \u0442\u0435\u0440\u0440\u0430\u0441\u0430 31\u043c2. \u041a\u0430\u0447\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0435 \u043f\u0440\u043e\u0435\u043a\u0442\u044b \u043e\u0442 \u0443\u043a\u0440\u0430\u0438\u043d\u0441\u043a\u0438\u0445 \u0430\u0440\u0445\u0438\u0442\u0435\u043a\u0442\u043e\u0440\u043e\u0432."],"rank_math_focus_keyword":["\u043f\u0440\u043e\u0435\u043a\u0442 \u0434\u0432\u0443\u0445\u044d\u0442\u0430\u0436\u043d\u043e\u0433\u043e \u0434\u043e\u043c\u0430 \u0441 \u0433\u0430\u0440\u0430\u0436\u043e\u043c"],"_last_translation_edit_mode":["native-editor"],"houzez_total_property_views":["866"],"houzez_views_by_date":["a:61:{s:10:\"04-28-2026\";i:1;s:10:\"04-29-2026\";i:4;s:10:\"04-30-2026\";i:1;s:10:\"05-02-2026\";i:2;s:10:\"05-03-2026\";i:1;s:10:\"05-04-2026\";i:3;s:10:\"05-05-2026\";i:3;s:10:\"05-08-2026\";i:2;s:10:\"05-10-2026\";i:2;s:10:\"05-11-2026\";i:2;s:10:\"05-13-2026\";i:1;s:10:\"05-14-2026\";i:1;s:10:\"05-15-2026\";i:2;s:10:\"05-16-2026\";i:1;s:10:\"05-18-2026\";i:2;s:10:\"05-19-2026\";i:2;s:10:\"05-21-2026\";i:2;s:10:\"05-24-2026\";i:1;s:10:\"05-25-2026\";i:3;s:10:\"05-26-2026\";i:1;s:10:\"05-27-2026\";i:2;s:10:\"05-28-2026\";i:3;s:10:\"05-29-2026\";i:1;s:10:\"05-30-2026\";i:1;s:10:\"05-31-2026\";i:2;s:10:\"06-01-2026\";i:1;s:10:\"06-03-2026\";i:1;s:10:\"06-04-2026\";i:2;s:10:\"06-06-2026\";i:1;s:10:\"06-07-2026\";i:1;s:10:\"06-08-2026\";i:3;s:10:\"06-09-2026\";i:3;s:10:\"06-10-2026\";i:3;s:10:\"06-11-2026\";i:4;s:10:\"06-12-2026\";i:2;s:10:\"06-13-2026\";i:1;s:10:\"06-14-2026\";i:2;s:10:\"06-15-2026\";i:3;s:10:\"06-16-2026\";i:5;s:10:\"06-17-2026\";i:2;s:10:\"06-18-2026\";i:3;s:10:\"06-19-2026\";i:3;s:10:\"06-20-2026\";i:1;s:10:\"06-24-2026\";i:2;s:10:\"06-25-2026\";i:3;s:10:\"06-26-2026\";i:1;s:10:\"06-29-2026\";i:2;s:10:\"06-30-2026\";i:2;s:10:\"07-01-2026\";i:3;s:10:\"07-02-2026\";i:2;s:10:\"07-03-2026\";i:3;s:10:\"07-05-2026\";i:2;s:10:\"07-06-2026\";i:3;s:10:\"07-08-2026\";i:3;s:10:\"07-09-2026\";i:2;s:10:\"07-10-2026\";i:2;s:10:\"07-11-2026\";i:2;s:10:\"07-12-2026\";i:2;s:10:\"07-13-2026\";i:1;s:10:\"07-14-2026\";i:1;s:10:\"07-15-2026\";i:1;}"],"houzez_recently_viewed":["2026-07-15 13:54:09"],"_edit_lock":["1783528363:2"],"rank_math_seo_score":["57"],"_edit_last":["2"],"fave_property_map":["0"],"realization_text_right":[""],"_realization_text_right":["field_615ab4a3d642e"],"_floor_plan_0_title":["field_617544b3064a2"],"_floor_plan_0_image":["field_615077d311d0b"],"_floor_plan_0_image_popup":["field_61792229e4347"],"floor_plan_0_table_0_col0":["1"],"_floor_plan_0_table_0_col0":["field_6179213f96639"],"floor_plan_0_table_0_col1":["\u0422\u0430\u043c\u0431\u0443\u0440"],"_floor_plan_0_table_0_col1":["field_6150781111d0d"],"floor_plan_0_table_0_col2":["4.00 \u043c2"],"_floor_plan_0_table_0_col2":["field_6150782b11d0e"],"floor_plan_0_table_1_col0":["2"],"_floor_plan_0_table_1_col0":["field_6179213f96639"],"floor_plan_0_table_1_col1":["\u0425\u043e\u043b\u043b"],"_floor_plan_0_table_1_col1":["field_6150781111d0d"],"floor_plan_0_table_1_col2":["6.13 \u043c2"],"_floor_plan_0_table_1_col2":["field_6150782b11d0e"],"floor_plan_0_table_2_col0":["3"],"_floor_plan_0_table_2_col0":["field_6179213f96639"],"floor_plan_0_table_2_col1":["\u041a\u043e\u043c\u043d\u0430\u0442\u0430 1"],"_floor_plan_0_table_2_col1":["field_6150781111d0d"],"floor_plan_0_table_2_col2":["13.34 \u043c2"],"_floor_plan_0_table_2_col2":["field_6150782b11d0e"],"floor_plan_0_table_3_col0":["4"],"_floor_plan_0_table_3_col0":["field_6179213f96639"],"floor_plan_0_table_3_col1":["\u041b\u0435\u0441\u0442\u043d\u0438\u0446\u0430"],"_floor_plan_0_table_3_col1":["field_6150781111d0d"],"floor_plan_0_table_3_col2":["4.40 \u043c2"],"_floor_plan_0_table_3_col2":["field_6150782b11d0e"],"floor_plan_0_table_4_col0":["5"],"_floor_plan_0_table_4_col0":["field_6179213f96639"],"floor_plan_0_table_4_col1":["\u041a\u043b\u0430\u0434\u043e\u0432\u0430\u044f"],"_floor_plan_0_table_4_col1":["field_6150781111d0d"],"floor_plan_0_table_4_col2":["3.63 \u043c2"],"_floor_plan_0_table_4_col2":["field_6150782b11d0e"],"floor_plan_0_table_5_col0":["6"],"_floor_plan_0_table_5_col0":["field_6179213f96639"],"floor_plan_0_table_5_col1":["\u041a\u0443\u0445\u043d\u044f"],"_floor_plan_0_table_5_col1":["field_6150781111d0d"],"floor_plan_0_table_5_col2":["18.74 \u043c2"],"_floor_plan_0_table_5_col2":["field_6150782b11d0e"],"floor_plan_0_table_6_col0":["7"],"_floor_plan_0_table_6_col0":["field_6179213f96639"],"floor_plan_0_table_6_col1":["\u0413\u043e\u0441\u0442\u0438\u043d\u0430\u044f"],"_floor_plan_0_table_6_col1":["field_6150781111d0d"],"floor_plan_0_table_6_col2":["32.80 \u043c2"],"_floor_plan_0_table_6_col2":["field_6150782b11d0e"],"floor_plan_0_table_7_col0":["8"],"_floor_plan_0_table_7_col0":["field_6179213f96639"],"floor_plan_0_table_7_col1":["\u0421\u0430\u043d\u0443\u0437\u0435\u043b"],"_floor_plan_0_table_7_col1":["field_6150781111d0d"],"floor_plan_0_table_7_col2":["4.64 \u043c2"],"_floor_plan_0_table_7_col2":["field_6150782b11d0e"],"floor_plan_0_table_8_col0":["9"],"_floor_plan_0_table_8_col0":["field_6179213f96639"],"floor_plan_0_table_8_col1":["\u041a\u043e\u0442\u0435\u043b\u044c\u043d\u0430\u044f"],"_floor_plan_0_table_8_col1":["field_6150781111d0d"],"floor_plan_0_table_8_col2":["7.62 \u043c2"],"_floor_plan_0_table_8_col2":["field_6150782b11d0e"],"floor_plan_0_table_9_col0":["10"],"_floor_plan_0_table_9_col0":["field_6179213f96639"],"floor_plan_0_table_9_col1":["\u0413\u0430\u0440\u0430\u0436"],"_floor_plan_0_table_9_col1":["field_6150781111d0d"],"floor_plan_0_table_9_col2":["33.30 \u043c2\r\n"],"_floor_plan_0_table_9_col2":["field_6150782b11d0e"],"floor_plan_0_table_10_col0":[""],"_floor_plan_0_table_10_col0":["field_6179213f96639"],"floor_plan_0_table_10_col1":["<b>\u041e\u0431\u0449\u0430\u044f \u043f\u043b\u043e\u0449\u0430\u0434\u044c:<\/b>"],"_floor_plan_0_table_10_col1":["field_6150781111d0d"],"floor_plan_0_table_10_col2":["<b>128.6 \u043c2<\/b>"],"_floor_plan_0_table_10_col2":["field_6150782b11d0e"],"floor_plan_0_table_11_col0":["11"],"_floor_plan_0_table_11_col0":["field_6179213f96639"],"floor_plan_0_table_11_col1":["\u0422\u0435\u0440\u0440\u0430\u0441\u0430"],"_floor_plan_0_table_11_col1":["field_6150781111d0d"],"floor_plan_0_table_11_col2":["31.12 \u043c2"],"_floor_plan_0_table_11_col2":["field_6150782b11d0e"],"_floor_plan_0_table":["field_615077f411d0c"],"_floor_plan_1_title":["field_617544b3064a2"],"_floor_plan_1_image":["field_615077d311d0b"],"_floor_plan_1_image_popup":["field_61792229e4347"],"floor_plan_1_table_0_col0":["1"],"_floor_plan_1_table_0_col0":["field_6179213f96639"],"floor_plan_1_table_0_col1":["\u0425\u043e\u043b\u043b"],"_floor_plan_1_table_0_col1":["field_6150781111d0d"],"floor_plan_1_table_0_col2":["9.98 \u043c2\r\n"],"_floor_plan_1_table_0_col2":["field_6150782b11d0e"],"floor_plan_1_table_1_col0":["2"],"_floor_plan_1_table_1_col0":["field_6179213f96639"],"floor_plan_1_table_1_col1":["\u0413\u0430\u0440\u0434\u0435\u0440\u043e\u0431"],"_floor_plan_1_table_1_col1":["field_6150781111d0d"],"floor_plan_1_table_1_col2":["6.53 \u043c2"],"_floor_plan_1_table_1_col2":["field_6150782b11d0e"],"floor_plan_1_table_2_col0":["3"],"_floor_plan_1_table_2_col0":["field_6179213f96639"],"floor_plan_1_table_2_col1":["\u041a\u043e\u043c\u043d\u0430\u0442\u0430 1"],"_floor_plan_1_table_2_col1":["field_6150781111d0d"],"floor_plan_1_table_2_col2":["13.30 \u043c2"],"_floor_plan_1_table_2_col2":["field_6150782b11d0e"],"floor_plan_1_table_3_col0":["4"],"_floor_plan_1_table_3_col0":["field_6179213f96639"],"floor_plan_1_table_3_col1":["\u041f\u0440\u0430\u0447\u0435\u0447\u043d\u0430\u044f"],"_floor_plan_1_table_3_col1":["field_6150781111d0d"],"floor_plan_1_table_3_col2":["3.22 \u043c2"],"_floor_plan_1_table_3_col2":["field_6150782b11d0e"],"floor_plan_1_table_4_col0":["5"],"_floor_plan_1_table_4_col0":["field_6179213f96639"],"floor_plan_1_table_4_col1":["\u0421\u0430\u043d\u0443\u0437\u0435\u043b"],"_floor_plan_1_table_4_col1":["field_6150781111d0d"],"floor_plan_1_table_4_col2":["8.85 \u043c2"],"_floor_plan_1_table_4_col2":["field_6150782b11d0e"],"floor_plan_1_table_5_col0":["6"],"_floor_plan_1_table_5_col0":["field_6179213f96639"],"floor_plan_1_table_5_col1":["\u041a\u043e\u043c\u043d\u0430\u0442\u0430 2"],"_floor_plan_1_table_5_col1":["field_6150781111d0d"],"floor_plan_1_table_5_col2":["13.76 \u043c2"],"_floor_plan_1_table_5_col2":["field_6150782b11d0e"],"floor_plan_1_table_6_col0":["7"],"_floor_plan_1_table_6_col0":["field_6179213f96639"],"floor_plan_1_table_6_col1":["\u041a\u043e\u043c\u043d\u0430\u0442\u0430 3"],"_floor_plan_1_table_6_col1":["field_6150781111d0d"],"floor_plan_1_table_6_col2":["10.36 \u043c2"],"_floor_plan_1_table_6_col2":["field_6150782b11d0e"],"floor_plan_1_table_7_col0":[""],"_floor_plan_1_table_7_col0":["field_6179213f96639"],"floor_plan_1_table_7_col1":["<b>\u041e\u0431\u0449\u0430\u044f \u043f\u043b\u043e\u0449\u0430\u0434\u044c:<\/b>"],"_floor_plan_1_table_7_col1":["field_6150781111d0d"],"floor_plan_1_table_7_col2":["<b>66.00 \u043c2<\/b>"],"_floor_plan_1_table_7_col2":["field_6150782b11d0e"],"_floor_plan_1_table":["field_615077f411d0c"],"_floor_plan":["field_615077a611d0a"],"3d_plan":[""],"_3d_plan":["field_614f72176cfed"],"_facades_0_image":["field_6150828a50494"],"_facades_1_image":["field_6150828a50494"],"_facades_2_image":["field_6150828a50494"],"_facades_3_image":["field_6150828a50494"],"_facades":["field_615081e750493"],"facades_text":["\u0422\u0435\u0445\u043d\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0445\u0430\u0440\u0430\u043a\u0442\u0435\u0440\u0438\u0441\u0442\u0438\u043a\u0438 \u0434\u043e\u043c\u0430 \u043f\u043e \u043f\u0440\u043e\u0435\u043a\u0442\u0443 \u041c\u0430\u0439\u043a\u043b:\r\n\r\n<span style=\"text-decoration: underline;\">\u041d\u0435\u0441\u0443\u0449\u0438\u0435 \u0441\u0442\u0435\u043d\u044b:<\/span> \u043a\u0435\u0440\u0430\u043c\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0431\u043b\u043e\u043a\u0438 380 \u043c\u043c., \u0443\u0442\u0435\u043f\u043b\u0435\u043d\u0438\u0435 \u043c\u0438\u043d\u0435\u0440\u0430\u043b\u044c\u043d\u043e\u0439 \u0432\u0430\u0442\u043e\u0439 150 \u043c\u043c.\r\n\r\n<span style=\"text-decoration: underline;\">\u0424\u0430\u0441\u0430\u0434\u044b:<\/span>\r\n<ul>\r\n \t<li>\u0412\u0430\u0440\u0438\u0430\u043d\u0442 1: \u0434\u0435\u0440\u0435\u0432\u044f\u043d\u043d\u044b\u0435 \u043f\u043b\u0430\u043d\u043a\u0438.<\/li>\r\n \t<li>\u0412\u0430\u0440\u0438\u0430\u043d\u0442 2: \u0444\u0430\u0441\u0430\u0434\u043d\u0430\u044f \u0448\u0442\u0443\u043a\u0430\u0442\u0443\u0440\u043a\u0430, \u043e\u043a\u0440\u0430\u0441\u043a\u0430.<\/li>\r\n<\/ul>\r\n<span style=\"text-decoration: underline;\">\u041f\u0435\u0440\u0435\u043a\u0440\u044b\u0442\u0438\u0435 \u043f\u0435\u0440\u0432\u043e\u0433\u043e \u044d\u0442\u0430\u0436\u0430:<\/span> \u043c\u043e\u043d\u043e\u043b\u0438\u0442.\r\n\r\n<span style=\"text-decoration: underline;\">\u041a\u0440\u043e\u0432\u0435\u043b\u044c\u043d\u044b\u0435 \u043c\u0430\u0442\u0435\u0440\u0438\u0430\u043b\u044b:<\/span> \u0434\u0435\u0440\u0435\u0432\u044f\u043d\u043d\u044b\u0435 \u0441\u0442\u0440\u043e\u043f\u0438\u043b\u0430 \u0441 \u0443\u0442\u0435\u043f\u043b\u0435\u043d\u0438\u0435\u043c \u043c\u0438\u043d\u0432\u0430\u0442\u043e\u0439 250 \u043c\u043c., \u043f\u043e\u043a\u0440\u044b\u0442\u0438\u0435 \u043a\u0440\u043e\u0432\u043b\u0438 \u2014 \u0444\u0430\u043b\u044c\u0446\u0435\u0432\u044b\u0439 \u043c\u0435\u0442\u0430\u043b\u043b."],"_facades_text":["field_617e748f1a091"],"realization":[""],"_realization":["field_61508bbdf6a16"],"heat_calculation":[""],"_heat_calculation":["field_617e86d51a013"],"rank_math_internal_links_processed":["1"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"fave_payment_status":["not_paid"],"_wpml_media_has_media":["1"],"rank_math_analytic_object_id":["17"],"_yoast_wpseo_primary_property_type":["120"],"_yoast_wpseo_primary_property_status":[""],"_yoast_wpseo_primary_property_feature":[""],"_yoast_wpseo_primary_property_label":["131"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_yoast_wpseo_wordproof_timestamp":[""],"fave_property_images":["21771","21774","21777","21780"]},"_links":{"self":[{"href":"https:\/\/dim4you.com.ua\/ru\/wp-json\/wp\/v2\/properties\/21819"}],"collection":[{"href":"https:\/\/dim4you.com.ua\/ru\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/dim4you.com.ua\/ru\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/dim4you.com.ua\/ru\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":5,"href":"https:\/\/dim4you.com.ua\/ru\/wp-json\/wp\/v2\/properties\/21819\/revisions"}],"predecessor-version":[{"id":21831,"href":"https:\/\/dim4you.com.ua\/ru\/wp-json\/wp\/v2\/properties\/21819\/revisions\/21831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dim4you.com.ua\/ru\/wp-json\/wp\/v2\/media\/21783"}],"wp:attachment":[{"href":"https:\/\/dim4you.com.ua\/ru\/wp-json\/wp\/v2\/media?parent=21819"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/dim4you.com.ua\/ru\/wp-json\/wp\/v2\/property_type?post=21819"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/dim4you.com.ua\/ru\/wp-json\/wp\/v2\/property_status?post=21819"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/dim4you.com.ua\/ru\/wp-json\/wp\/v2\/property_feature?post=21819"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/dim4you.com.ua\/ru\/wp-json\/wp\/v2\/property_label?post=21819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}